{"id":75,"date":"2022-04-06T17:08:09","date_gmt":"2022-04-06T17:08:09","guid":{"rendered":"http:\/\/odewinery.com\/?page_id=75"},"modified":"2024-09-27T11:18:08","modified_gmt":"2024-09-27T11:18:08","slug":"about","status":"publish","type":"page","link":"https:\/\/odewinery.com\/pt\/about\/","title":{"rendered":"Sobre"},"content":{"rendered":"<div id=\"fws_6a04c3dd96b6b\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-content  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle parallax_section  bottom_padding_phone_50pct\"  style=\"padding-top: 240px; padding-bottom: 240px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"fade-in\" data-bg-overlay=\"false\"><div class=\"inner-wrap using-image\"><div class=\"row-bg using-image\" data-parallax-speed=\"fast\" style=\"background-image: url(https:\/\/odewinery.com\/wp-content\/uploads\/2023\/01\/about.jpg); background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\r\n\t\t<div id=\"contact\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row  fullpage\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-5 wpb_column column_container vc_column_container col centered-text no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<h2 style=\"text-align: left\" class=\"vc_custom_heading\" >About us<\/h2>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1727435823131\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"font-weight: 400;\">The 96-hectare Ode property was acquired by Immerso Collective group, with the aim of creating a project that would bring the deserved visibility to the region and to its extensive wine culture through Ode Winery and Ode Farm &amp; Living.<\/p>\n<p style=\"font-weight: 400;\">Immerso Collective is a company focused on luxury and sustainability. It was created by David Clarkin, who has more than thirty years of experience in investing and developing real estate in the Asian and Australian markets, and with perspectives for the future, and Andrew Homan, a lawyer by training but with extensive experience in different industries, namely in the management of real estate investment funds. The projects developed by Immerso always aim to boost the region and the community in which they operate with integration approaches, ranging from commercial and residential properties to offers more directed to tourism, in a perfect connection between care and respect for the environment and high standards of luxury and comfort.<\/p>\n<p style=\"font-weight: 400;\">In 2021, the company began operating in Portugal, its first location in Europe, with the acquisition of what is now Ode Winery, Farm &amp; Living.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\r\n\t\t<div id=\"fws_6a04c3dd99b43\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-5 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-5 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\r\n\t\t<div id=\"contact\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"3%\" data-bottom-percent=\"3%\"  class=\"wpb_row vc_row-fluid vc_row  fullpage\"  style=\"padding-top: calc(100vw * 0.03); padding-bottom: calc(100vw * 0.03); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col padding-5-percent inherit_tablet inherit_phone\"  data-padding-pos=\"bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 0.5px; height: 1px; margin-bottom: 0.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"default\" class=\"divider-border\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1674734704150\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h3 style=\"text-align: center;\">Get in touch for additional information on Ode Winery;<br \/>\nOde Farm and Living or any other Immerso Collective ventures.<\/h3>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f668-o1\" lang=\"en\" dir=\"ltr\" data-wpcf7-id=\"668\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/pages\/75#wpcf7-f668-o1\" method=\"post\" class=\"wpcf7-form init 36d86e6b58cd cmatic-conn cmatic-aud-1 cmatic-mapd0-0 cmatic-v097803 cmatic-sent-0 cmatic-total-78\" aria-label=\"Formul\u00e1rio de contacto\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/75#wpcf7-f668-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"668\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f668-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"col\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Last name\" value=\"\" type=\"text\" name=\"your-last-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Phone number (optional)\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"col\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Your Message\" name=\"your-message\"><\/textarea><\/span><br \/>\n\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"event-id\" \/>\n\t<\/p>\n\t<div class=\"policy-radio\">\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"policy\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"policy[]\" value=\"I have read and accepted the\" \/><span class=\"wpcf7-list-item-label\">I have read and accepted the<\/span><\/span><\/span><\/span><a href=\"\/pt\/privacy-policy\/\">Pol\u00edtica de Privacidade<\/a>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"housesButton\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner neolitButton\" type=\"submit\" value=\"Send\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\r\n\t\t<div id=\"fws_6a04c3dd9d83c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<a class=\"nectar-button small regular accent-color  regular-button button-sticky\"  style=\"color: #ffffff; background-color: #b7752c;\"  href=\"\/pt\/experiences\/\" data-color-override=\"#b7752c\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Marque a Sua Visita<\/span><\/a>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"About us The 96-hectare Ode property was acquired by Immerso Collective group, with the aim of creating a project that would bring the deserved visibility to the region and to...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-75","page","type-page","status-publish"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/odewinery.com\/pt\/wp-json\/wp\/v2\/pages\/75","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odewinery.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odewinery.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odewinery.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odewinery.com\/pt\/wp-json\/wp\/v2\/comments?post=75"}],"version-history":[{"count":103,"href":"https:\/\/odewinery.com\/pt\/wp-json\/wp\/v2\/pages\/75\/revisions"}],"predecessor-version":[{"id":2119,"href":"https:\/\/odewinery.com\/pt\/wp-json\/wp\/v2\/pages\/75\/revisions\/2119"}],"wp:attachment":[{"href":"https:\/\/odewinery.com\/pt\/wp-json\/wp\/v2\/media?parent=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}